{"id":108,"count":1,"description":"","link":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/","name":"giro d&#8217;italia","slug":"giro-ditalia-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>giro d&#8217;italia Archivi - Chalet Nata<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"giro d&#8217;italia Archivi - Chalet Nata\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Chalet Nata\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/\",\"url\":\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/\",\"name\":\"giro d&#8217;italia Archivi - Chalet Nata\",\"isPartOf\":{\"@id\":\"https:\/\/www.chaletnata.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.chaletnata.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"giro d&#8217;italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.chaletnata.com\/en\/#website\",\"url\":\"https:\/\/www.chaletnata.com\/en\/\",\"name\":\"Chalet Nata\",\"description\":\"Appartamenti Turistici in Val di Fassa - Apartmens Dolomites - Ferienwhonung Dolomiten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.chaletnata.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"giro d&#8217;italia Archivi - Chalet Nata","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/","og_locale":"en_US","og_type":"article","og_title":"giro d&#8217;italia Archivi - Chalet Nata","og_url":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/","og_site_name":"Chalet Nata","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/","url":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/","name":"giro d&#8217;italia Archivi - Chalet Nata","isPartOf":{"@id":"https:\/\/www.chaletnata.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.chaletnata.com\/en\/tag\/giro-ditalia-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.chaletnata.com\/en\/"},{"@type":"ListItem","position":2,"name":"giro d&#8217;italia"}]},{"@type":"WebSite","@id":"https:\/\/www.chaletnata.com\/en\/#website","url":"https:\/\/www.chaletnata.com\/en\/","name":"Chalet Nata","description":"Appartamenti Turistici in Val di Fassa - Apartmens Dolomites - Ferienwhonung Dolomiten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.chaletnata.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.chaletnata.com\/en\/wp-json\/wp\/v2\/tags\/108\/"}],"collection":[{"href":"https:\/\/www.chaletnata.com\/en\/wp-json\/wp\/v2\/tags\/"}],"about":[{"href":"https:\/\/www.chaletnata.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag\/"}],"wp:post_type":[{"href":"https:\/\/www.chaletnata.com\/en\/wp-json\/wp\/v2\/posts\/?tags=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}